{"id":26,"count":9,"description":"","link":"https:\/\/pureselfhealing.com\/index.php\/tag\/well-being\/","name":"well being","slug":"well-being","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/pureselfhealing.com\/index.php\/wp-json\/wp\/v2\/tags\/26"}],"collection":[{"href":"https:\/\/pureselfhealing.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/pureselfhealing.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/pureselfhealing.com\/index.php\/wp-json\/wp\/v2\/posts?tags=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}