{"id":388,"count":1,"description":"","link":"https:\/\/pureselfhealing.com\/index.php\/tag\/caffeine-sensitivity\/","name":"caffeine sensitivity","slug":"caffeine-sensitivity","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/pureselfhealing.com\/index.php\/wp-json\/wp\/v2\/tags\/388"}],"collection":[{"href":"https:\/\/pureselfhealing.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/pureselfhealing.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/pureselfhealing.com\/index.php\/wp-json\/wp\/v2\/posts?tags=388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}